{"id":5239,"date":"2025-09-09T15:44:42","date_gmt":"2025-09-09T13:44:42","guid":{"rendered":"https:\/\/www.myanmar-stiftung.de\/?p=5239"},"modified":"2025-09-21T19:35:28","modified_gmt":"2025-09-21T17:35:28","slug":"whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht","status":"publish","type":"post","link":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/","title":{"rendered":"&#8222;Whispering Seed&#8220; &#8211; Nachhaltigkeit in Bildung und Ern\u00e4hrung"},"content":{"rendered":"<div>Das Projekt Whispering Seed liegt in Kalaw\/Shan State, oberhalb des Inle Lake, und umfasst zwei Training Center (Sprouting Seeds, Whispering Earth), die auf nachhaltige Landwirtschaft ausgerichtet sind und Lehrer aus dem ganzen Land ausbilden. Durch das gro\u00dfe Netzwerk konnten nach dem schweren Erdbeben Ende M\u00e4rz rund 200 Familien in den betroffenen Gebieten mit Nahrung versorgt werden.<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/Whispering-Seed-Update-Sept-2025.pdf\">Whispering Seed Update Sept 2025<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Projekt Whispering Seed liegt in Kalaw\/Shan State, oberhalb des Inle Lake, und umfasst zwei Training Center (Sprouting Seeds, Whispering Earth), die auf nachhaltige Landwirtschaft ausgerichtet sind und Lehrer aus dem ganzen Land ausbilden. Durch das gro\u00dfe Netzwerk konnten nach dem schweren Erdbeben Ende M\u00e4rz rund 200 Familien in den betroffenen Gebieten mit Nahrung versorgt&hellip;<\/p>\n","protected":false},"author":5,"featured_media":5268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Whispering Seed&quot; - Nachhaltigkeit in Bildung und Ern\u00e4hrung - Myanmar-Stiftung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Whispering Seed&quot; - Nachhaltigkeit in Bildung und Ern\u00e4hrung - Myanmar-Stiftung\" \/>\n<meta property=\"og:description\" content=\"Das Projekt Whispering Seed liegt in Kalaw\/Shan State, oberhalb des Inle Lake, und umfasst zwei Training Center (Sprouting Seeds, Whispering Earth), die auf nachhaltige Landwirtschaft ausgerichtet sind und Lehrer aus dem ganzen Land ausbilden. Durch das gro\u00dfe Netzwerk konnten nach dem schweren Erdbeben Ende M\u00e4rz rund 200 Familien in den betroffenen Gebieten mit Nahrung versorgt&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/\" \/>\n<meta property=\"og:site_name\" content=\"Myanmar-Stiftung\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-09T13:44:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-21T17:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/WS1-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Veronika Hofmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veronika Hofmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/\"},\"author\":{\"name\":\"Veronika Hofmann\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/#\\\/schema\\\/person\\\/7e26a6d6128ff41ff1a474936ff68f0f\"},\"headline\":\"&#8222;Whispering Seed&#8220; &#8211; Nachhaltigkeit in Bildung und Ern\u00e4hrung\",\"datePublished\":\"2025-09-09T13:44:42+00:00\",\"dateModified\":\"2025-09-21T17:35:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/\"},\"wordCount\":71,\"image\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WS1-2-scaled.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/\",\"url\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/\",\"name\":\"\\\"Whispering Seed\\\" - Nachhaltigkeit in Bildung und Ern\u00e4hrung - Myanmar-Stiftung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WS1-2-scaled.jpg\",\"datePublished\":\"2025-09-09T13:44:42+00:00\",\"dateModified\":\"2025-09-21T17:35:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/#\\\/schema\\\/person\\\/7e26a6d6128ff41ff1a474936ff68f0f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WS1-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WS1-2-scaled.jpg\",\"width\":2560,\"height\":1284},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8222;Whispering Seed&#8220; &#8211; Nachhaltigkeit in Bildung und Ern\u00e4hrung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/#website\",\"url\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/\",\"name\":\"Myanmar-Stiftung\",\"description\":\"Hilfe f\u00fcr Kinder in Myanmar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/#\\\/schema\\\/person\\\/7e26a6d6128ff41ff1a474936ff68f0f\",\"name\":\"Veronika Hofmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b74c049c88508178ceeb67ad92ab7a23ec4dc97071586363a9064bc5f0706e0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b74c049c88508178ceeb67ad92ab7a23ec4dc97071586363a9064bc5f0706e0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b74c049c88508178ceeb67ad92ab7a23ec4dc97071586363a9064bc5f0706e0?s=96&d=mm&r=g\",\"caption\":\"Veronika Hofmann\"},\"url\":\"https:\\\/\\\/www.myanmar-stiftung.de\\\/index.php\\\/author\\\/hofmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Whispering Seed\" - Nachhaltigkeit in Bildung und Ern\u00e4hrung - Myanmar-Stiftung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/","og_locale":"de_DE","og_type":"article","og_title":"\"Whispering Seed\" - Nachhaltigkeit in Bildung und Ern\u00e4hrung - Myanmar-Stiftung","og_description":"Das Projekt Whispering Seed liegt in Kalaw\/Shan State, oberhalb des Inle Lake, und umfasst zwei Training Center (Sprouting Seeds, Whispering Earth), die auf nachhaltige Landwirtschaft ausgerichtet sind und Lehrer aus dem ganzen Land ausbilden. Durch das gro\u00dfe Netzwerk konnten nach dem schweren Erdbeben Ende M\u00e4rz rund 200 Familien in den betroffenen Gebieten mit Nahrung versorgt&hellip;","og_url":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/","og_site_name":"Myanmar-Stiftung","article_published_time":"2025-09-09T13:44:42+00:00","article_modified_time":"2025-09-21T17:35:28+00:00","og_image":[{"width":2560,"height":1284,"url":"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/WS1-2-scaled.jpg","type":"image\/jpeg"}],"author":"Veronika Hofmann","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Veronika Hofmann","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#article","isPartOf":{"@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/"},"author":{"name":"Veronika Hofmann","@id":"https:\/\/www.myanmar-stiftung.de\/#\/schema\/person\/7e26a6d6128ff41ff1a474936ff68f0f"},"headline":"&#8222;Whispering Seed&#8220; &#8211; Nachhaltigkeit in Bildung und Ern\u00e4hrung","datePublished":"2025-09-09T13:44:42+00:00","dateModified":"2025-09-21T17:35:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/"},"wordCount":71,"image":{"@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/WS1-2-scaled.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/","url":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/","name":"\"Whispering Seed\" - Nachhaltigkeit in Bildung und Ern\u00e4hrung - Myanmar-Stiftung","isPartOf":{"@id":"https:\/\/www.myanmar-stiftung.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#primaryimage"},"image":{"@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/WS1-2-scaled.jpg","datePublished":"2025-09-09T13:44:42+00:00","dateModified":"2025-09-21T17:35:28+00:00","author":{"@id":"https:\/\/www.myanmar-stiftung.de\/#\/schema\/person\/7e26a6d6128ff41ff1a474936ff68f0f"},"breadcrumb":{"@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#primaryimage","url":"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/WS1-2-scaled.jpg","contentUrl":"https:\/\/www.myanmar-stiftung.de\/wp-content\/uploads\/2025\/09\/WS1-2-scaled.jpg","width":2560,"height":1284},{"@type":"BreadcrumbList","@id":"https:\/\/www.myanmar-stiftung.de\/index.php\/whispering-seed-ein-projekt-das-fuer-nachhaltigkeit-in-bildung-und-ernaehrung-steht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.myanmar-stiftung.de\/"},{"@type":"ListItem","position":2,"name":"&#8222;Whispering Seed&#8220; &#8211; Nachhaltigkeit in Bildung und Ern\u00e4hrung"}]},{"@type":"WebSite","@id":"https:\/\/www.myanmar-stiftung.de\/#website","url":"https:\/\/www.myanmar-stiftung.de\/","name":"Myanmar-Stiftung","description":"Hilfe f\u00fcr Kinder in Myanmar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myanmar-stiftung.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.myanmar-stiftung.de\/#\/schema\/person\/7e26a6d6128ff41ff1a474936ff68f0f","name":"Veronika Hofmann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8b74c049c88508178ceeb67ad92ab7a23ec4dc97071586363a9064bc5f0706e0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b74c049c88508178ceeb67ad92ab7a23ec4dc97071586363a9064bc5f0706e0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b74c049c88508178ceeb67ad92ab7a23ec4dc97071586363a9064bc5f0706e0?s=96&d=mm&r=g","caption":"Veronika Hofmann"},"url":"https:\/\/www.myanmar-stiftung.de\/index.php\/author\/hofmann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/posts\/5239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/comments?post=5239"}],"version-history":[{"count":4,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/posts\/5239\/revisions"}],"predecessor-version":[{"id":5269,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/posts\/5239\/revisions\/5269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/media\/5268"}],"wp:attachment":[{"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/media?parent=5239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/categories?post=5239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myanmar-stiftung.de\/index.php\/wp-json\/wp\/v2\/tags?post=5239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}